{"id":50921,"count":1,"description":"","link":"https:\/\/anba.com.br\/en\/tag\/lebanese-brazilian-medical-association\/","name":"Lebanese-Brazilian Medical Association","slug":"lebanese-brazilian-medical-association","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/anba.com.br\/en\/wp-json\/wp\/v2\/tags\/50921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anba.com.br\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/anba.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/anba.com.br\/en\/wp-json\/wp\/v2\/posts?tags=50921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}